{"id":68,"count":0,"description":"","link":"https:\/\/www.hdmoviereviews.com\/index.php\/category\/movie-deals\/","name":"Movie Deals","slug":"movie-deals","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.hdmoviereviews.com\/index.php\/wp-json\/wp\/v2\/categories\/68","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hdmoviereviews.com\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.hdmoviereviews.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.hdmoviereviews.com\/index.php\/wp-json\/wp\/v2\/posts?categories=68"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}